{"id":693,"date":"2023-05-05T13:59:59","date_gmt":"2023-05-05T13:59:59","guid":{"rendered":"https:\/\/wp.themerange.net\/conat\/?page_id=693"},"modified":"2023-05-11T09:37:39","modified_gmt":"2023-05-11T09:37:39","slug":"price","status":"publish","type":"page","link":"https:\/\/wp.themerange.net\/conat\/price\/","title":{"rendered":"Price"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"693\" class=\"elementor elementor-693\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e257ea elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0e257ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e13f6b2\" data-id=\"e13f6b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e327a7 elementor-widget elementor-widget-conat_price_table_v2\" data-id=\"3e327a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"conat_price_table_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        \n        <!-- Price Two -->\n        <section class=\"price-two\">\n            <div class=\"price-two_pattern-one\" style=\"background-image:url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/pattern-24.png)\"><\/div>            <div class=\"price-two_pattern-two\" style=\"background-image:url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/pattern-24.png)\"><\/div>            <div class=\"auto-container\">\n                <div class=\"sec-title title-anim centered\">\n                    <div class=\"sec-title_title\">Conference Ticket Price<\/div>\n                    <h2 class=\"sec-title_heading\">Conference Tickets Now<\/h2>\n                <\/div>\n                <div class=\"row clearfix\">\n                    <!-- Price Block Two -->\n                    <div class=\"price-block_two col-lg-4 col-md-6 col-sm-12\">\n                        <div class=\"price-block_two-inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\n                            <span class=\"price-block_two-color_layer\"><\/span>\n                            <div class=\"price-block_two-time\">FIRST DAY<\/div>\n                            <div class=\"price-block_two-title\">Standard Pass<\/div>\n                            <div class=\"price-block_two-date\">$120<\/div>\n                            <div class=\"price-block_two-content\">\n                                                                <ul class=\"price-block_two-options\">\n                                \t                                    <li ><strong>Full Conference<\/strong>(Includes workshop, coffee etc)<\/li>\n                                                                        <li class=\"light\"><strong>Live Videos<\/strong>(Can access online free)<\/li>\n                                                                        <li class=\"light\"><strong>Meet Speaker<\/strong>(Ask questions privately)<\/li>\n                                                                    <\/ul>\n                                                                \n                                                                <div class=\"price-block_two-button\">\n                                \t<a href=\"#\" class=\"theme-btn btn-style-one\">\n\t\t<span class=\"btn-wrap\">\n\t\t\t<span class=\"text-one\">Buy Ticket<\/span>\n\t\t\t<span class=\"text-two\">Buy Ticket<\/span>\n\t\t<\/span>\n\t<\/a>                                <\/div>\n                                                                <div class=\"price-block_two-charges\">Our prices includes 10% charges<\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    \n                    <!-- Price Block Two -->\n                    <div class=\"price-block_two col-lg-4 col-md-6 col-sm-12\">\n                        <div class=\"price-block_two-inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\n                            <span class=\"price-block_two-color_layer\"><\/span>\n                            <div class=\"price-block_two-time\">second DAY<\/div>\n                            <div class=\"price-block_two-title\">Flexible Pass<\/div>\n                            <div class=\"price-block_two-date\">$220<\/div>\n                            <div class=\"price-block_two-content\">\n                                                                <ul class=\"price-block_two-options\">\n                                \t                                    <li ><strong>Full Conference<\/strong>(Includes workshop, coffee etc)<\/li>\n                                                                        <li ><strong>Live Videos<\/strong>(Can access online free)<\/li>\n                                                                        <li class=\"light\"><strong>Meet Speaker<\/strong>(Ask questions privately)<\/li>\n                                                                    <\/ul>\n                                                                \n                                                                <div class=\"price-block_two-button\">\n                                \t<a href=\"#\" class=\"theme-btn btn-style-one\">\n\t\t<span class=\"btn-wrap\">\n\t\t\t<span class=\"text-one\">Buy Ticket<\/span>\n\t\t\t<span class=\"text-two\">Buy Ticket<\/span>\n\t\t<\/span>\n\t<\/a>                                <\/div>\n                                                                <div class=\"price-block_two-charges\">Our prices includes 10% charges<\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    \n                    <!-- Price Block Two -->\n                    <div class=\"price-block_two col-lg-4 col-md-6 col-sm-12\">\n                        <div class=\"price-block_two-inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\n                            <span class=\"price-block_two-color_layer\"><\/span>\n                            <div class=\"price-block_two-time\">third DAY<\/div>\n                            <div class=\"price-block_two-title\">Business Pass<\/div>\n                            <div class=\"price-block_two-date\">$320<\/div>\n                            <div class=\"price-block_two-content\">\n                                                                <ul class=\"price-block_two-options\">\n                                \t                                    <li ><strong>Full Conference<\/strong>(Includes workshop, coffee etc)<\/li>\n                                                                        <li ><strong>Live Videos<\/strong>(Can access online free)<\/li>\n                                                                        <li ><strong>Meet Speaker<\/strong>(Ask questions privately)<\/li>\n                                                                    <\/ul>\n                                                                \n                                                                <div class=\"price-block_two-button\">\n                                \t<a href=\"#\" class=\"theme-btn btn-style-one\">\n\t\t<span class=\"btn-wrap\">\n\t\t\t<span class=\"text-one\">Buy Ticket<\/span>\n\t\t\t<span class=\"text-two\">Buy Ticket<\/span>\n\t\t<\/span>\n\t<\/a>                                <\/div>\n                                                                <div class=\"price-block_two-charges\">Our prices includes 10% charges<\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/section>\n        <!-- End Price Two -->\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59d3871 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"59d3871\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34b1e1a\" data-id=\"34b1e1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69ae5c9 elementor-widget elementor-widget-conat_price_table_v3\" data-id=\"69ae5c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"conat_price_table_v3.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        \n        <!-- Price Three -->\n        <section class=\"price-three\" style=\"background-image:url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/9.jpg)\">\n            <div class=\"auto-container\">\n                <div class=\"sec-title light centered\">\n                    <div class=\"sec-title_title\">Conference Ticket Price<\/div>\n                    <h2 class=\"sec-title_heading\">Get You a Conference <br> Tickets Now<\/h2>\n                <\/div>\n                \n                <div class=\"row clearfix\">\n                    <!-- Price Block Three -->\n                    <div class=\"price-block_three col-lg-4 col-md-6 col-sm-12\">\n                        <div class=\"price-block_three-inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\n                            <div class=\"price-block_three-pattern\" style=\"background-image:url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/price-bg-1.png)\"><\/div>                            <div class=\"price-block_three-title\">Standard Pass<\/div>\n                            <div class=\"price-block_three-price\">$120 <span>1 DAY<\/span><\/div>\n                                                        <ul class=\"price-block_three-options\">\n                            \t                                <li ><strong>Full Conference<\/strong>(Includes workshop, coffee etc)<\/li>\n                                                                <li class=\"light\"><strong>Live Videos<\/strong>(Can access online free)<\/li>\n                                                                <li class=\"light\"><strong>Meet Speaker<\/strong>(Ask questions privately)<\/li>\n                                                            <\/ul>\n                                                        \n                                                        <div class=\"price-block_three-button\">\n                                <a href=\"#\" class=\"theme-btn btn-style-two\">\n\t\t<span class=\"btn-wrap\">\n\t\t\t<span class=\"text-one\">Buy Ticket<\/span>\n\t\t\t<span class=\"text-two\">Buy Ticket<\/span>\n\t\t<\/span>\n\t<\/a>                            <\/div>\n                                                        <div class=\"price-block_three-charges\">Our prices includes 10% charges<\/div>\n                        <\/div>\n                    <\/div>\n                    \n                    <!-- Price Block Three -->\n                    <div class=\"price-block_three col-lg-4 col-md-6 col-sm-12\">\n                        <div class=\"price-block_three-inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\n                            <div class=\"price-block_three-pattern\" style=\"background-image:url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/price-bg-2.png)\"><\/div>                            <div class=\"price-block_three-title\">Standard Pass<\/div>\n                            <div class=\"price-block_three-price\">$220 <span>2 Days<\/span><\/div>\n                                                        <ul class=\"price-block_three-options\">\n                            \t                                <li ><strong>Full Conference<\/strong>(Includes workshop, coffee etc)<\/li>\n                                                                <li ><strong>Live Videos<\/strong>(Can access online free)<\/li>\n                                                                <li class=\"light\"><strong>Meet Speaker<\/strong>(Ask questions privately)<\/li>\n                                                            <\/ul>\n                                                        \n                                                        <div class=\"price-block_three-button\">\n                                <a href=\"#\" class=\"theme-btn btn-style-two\">\n\t\t<span class=\"btn-wrap\">\n\t\t\t<span class=\"text-one\">Buy Ticket<\/span>\n\t\t\t<span class=\"text-two\">Buy Ticket<\/span>\n\t\t<\/span>\n\t<\/a>                            <\/div>\n                                                        <div class=\"price-block_three-charges\">Our prices includes 10% charges<\/div>\n                        <\/div>\n                    <\/div>\n                    \n                    <!-- Price Block Three -->\n                    <div class=\"price-block_three col-lg-4 col-md-6 col-sm-12\">\n                        <div class=\"price-block_three-inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\n                            <div class=\"price-block_three-pattern\" style=\"background-image:url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/price-bg-3.png)\"><\/div>                            <div class=\"price-block_three-title\"> Standard Pass<\/div>\n                            <div class=\"price-block_three-price\">$320 <span>3 Days<\/span><\/div>\n                                                        <ul class=\"price-block_three-options\">\n                            \t                                <li ><strong>Full Conference<\/strong>(Includes workshop, coffee etc)<\/li>\n                                                                <li ><strong>Live Videos<\/strong>(Can access online free)<\/li>\n                                                                <li ><strong>Meet Speaker<\/strong>(Ask questions privately)<\/li>\n                                                            <\/ul>\n                                                        \n                                                        <div class=\"price-block_three-button\">\n                                <a href=\"#\" class=\"theme-btn btn-style-two\">\n\t\t<span class=\"btn-wrap\">\n\t\t\t<span class=\"text-one\">Buy Ticket<\/span>\n\t\t\t<span class=\"text-two\">Buy Ticket<\/span>\n\t\t<\/span>\n\t<\/a>                            <\/div>\n                                                        <div class=\"price-block_three-charges\">Our prices includes 10% charges<\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/section>\n        <!-- End Price Three -->\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf4eab elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3cf4eab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c28fd6\" data-id=\"4c28fd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e8c1f5 elementor-widget elementor-widget-conat_subscriber\" data-id=\"2e8c1f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"conat_subscriber.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        \n                \n        <!-- Subscribe One -->\n        <section class=\"subscribe-two\" style=\"background-image: url(https:\/\/wp.themerange.net\/conat\/wp-content\/uploads\/2023\/05\/6-1.jpg)\">\n            <div class=\"auto-container\">\n                <div class=\"inner-container\">\n                    <div class=\"row clearfix\">\n                        <div class=\"subscribe-two_title-column col-lg-6 col-md-12 col-sm-12\">\n                            <div class=\"subscribe-two_title\">Get The Latest Updates<\/div>\n                            <h3 class=\"subscribe-two_heading\">Signup For Newsletter<\/h3>\n                        <\/div>\n                        \n                        <!-- Form Column -->\n                        <div class=\"form-column col-lg-6 col-md-12 col-sm-12\">\n                                                        <!-- Subscribe Box -->\n                            <div class=\"subscribe-box style-two\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f285-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"285\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/conat\/wp-json\/wp\/v2\/pages\/693#wpcf7-f285-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"285\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f285-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-group\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Email Address ...\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Subscribe\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                            <\/div>\n                                                    <\/div>\n                        \n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/section>\n        <!-- End Subscribe One -->\n                \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conference Ticket Price Conference Tickets Now FIRST DAY Standard Pass $120 Full Conference(Includes workshop, coffee etc) Live Videos(Can access online free) Meet Speaker(Ask questions privately) Buy Ticket Buy Ticket Our [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-default-elementor.php","meta":{"footnotes":""},"class_list":["post-693","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/pages\/693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/comments?post=693"}],"version-history":[{"count":13,"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/pages\/693\/revisions"}],"predecessor-version":[{"id":1222,"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/pages\/693\/revisions\/1222"}],"wp:attachment":[{"href":"https:\/\/wp.themerange.net\/conat\/wp-json\/wp\/v2\/media?parent=693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}